{"id":109,"date":"2024-05-16T14:02:48","date_gmt":"2024-05-16T12:02:48","guid":{"rendered":"https:\/\/www.schuelerrabatte.com\/blog\/?p=109&d=10da34aa5dc8cb82fd2cf210e51fd46f0176c360"},"modified":"2024-06-10T16:06:40","modified_gmt":"2024-06-10T14:06:40","slug":"gratis-klimaticket","status":"publish","type":"post","link":"https:\/\/www.schuelerrabatte.com\/blog\/gratis-klimaticket\/","title":{"rendered":"Jetzt bekommst du das KlimaTicket 1 Jahr gratis!"},"content":{"rendered":"<p>Gro\u00dfartige Neuigkeiten: Das <strong>gratis KlimaTicket \u00d618<\/strong> kann dich ab 1. Juli \u00f6sterreichweit mit den \u00d6ffis kutschieren! Ob auch du Anspruch hast, wie du es anfordern kannst, zu welchem Zeitpunkt dein kostenloses Jahr startet und alle anderen wichtigen Fragen beantworten wir dir gleich hier!<\/p>\n<p><!--more--><\/p>\n<h3>Habe ich Anspruch auf das kostenlose KlimaTicket \u00d618?<\/h3>\n<p>Ja, wenn du<\/p>\n<ul>\n<li>\u00fcber einen Wohnsitz in \u00d6sterreich verf\u00fcgst und<\/li>\n<li>du im Jahr 2024 deinen 18. Geburtstag feierst bzw. schon gefeiert hast. Wirst du im Jahr 2025 18 Jahre alt bzw. noch sp\u00e4ter, dann gilt das Angebot f\u00fcr dich ab jenem Zeitpunkt.<\/li>\n<\/ul>\n<h3>Wie lange gilt das gratis KlimaTicket?<\/h3>\n<p>Ab Ausstellungsdatum 1 Jahr.<\/p>\n<p class=\"p1\"><span class=\"s1\"><div class=\"voucher-embed-iframe-wrapper\"><iframe title=\"Gutschein Frame\" data-src=\"https:\/\/www.schuelerrabatte.com\/at\/external\/widget\/best?blog=1\" class=\"voucher-embed-iframe embed-blog lazy-load\" scrolling=\"no\" seamless=\"seamless\" frameBorder=\"0\" width=\"300\" height=\"160\" name=\"GutscheinFrame\"><\/iframe><\/div><\/span><\/p>\n<h3>Kann ich selbst den Zeitpunkt bestimmen oder gilt es ab meinem Geburtstag?<\/h3>\n<p>Es steht dir <strong>frei, den Zeitpunkt selbst zu w\u00e4hlen<\/strong>, ab dem dein kostenloses KlimaTicket f\u00fcr 1 Jahr gelten soll (1 Jahr am St\u00fcck, aufteilen geht nicht). Du musst es allerdings <strong>innerhalb von drei Jahren<\/strong> ab deinem 18. Geburtstag einl\u00f6sen.<\/p>\n<p>Fr\u00fchestm\u00f6glicher G\u00fcltigkeitsbeginn ist also der Tag deines 18. Geburtstags, der sp\u00e4testm\u00f6gliche der Tag vor deinem 21. Geburtstag.<\/p>\n<p><strong>Tipp:<\/strong> Profitierst du noch eine Zeit lang von Sch\u00fclererm\u00e4\u00dfigungen bei den \u00f6ffentlichen Verkehrsmitteln, dann warte mit deinem Gratisjahr ruhig noch ein bisschen!<\/p>\n<p>Du kannst das Ticket fr\u00fchestens einen Monat vor G\u00fcltigkeitsbeginn anfordern.<\/p>\n<h3>Wie hole ich mir mein kostenloses KlimaTicket \u00d618?<\/h3>\n<p>Da die Bundesregierung ja nicht wei\u00df, wann du dein KlimaTicket \u00d618 nutzen m\u00f6chtest (siehe oben), erfolgt die Ausstellung nicht automatisch. Du musst es dir <strong>selbstst\u00e4ndig<\/strong> und<strong> pers\u00f6nlich<\/strong> bei Vertriebs- und Servicestellen des KlimaTicket \u00d6 holen. <a href=\"https:\/\/www.klimaticket.at\/partner\/\" target=\"_blank\" rel=\"noopener\">Diese findest du hier!<\/a><\/p>\n<p><strong>Beachte 2 Dinge:<\/strong> Online bestellen ist nicht m\u00f6glich! Und aktuell kannst du dir das KlimaTicket \u00d6 18 leider <em>nicht<\/em> bei den Wiener Linien besorgen. G\u00fcltig f\u00fcr die Wiener \u00d6ffis ist das Ticket aber nat\u00fcrlich trotzdem!<\/p>\n<p><strong>Was musst du f\u00fcr die Beantragung mitnehmen?<\/strong><\/p>\n<ul>\n<li>Deine aktuelle Meldebest\u00e4tigung \u00fcber einen Wohnsitz in \u00d6sterreich (nicht \u00e4lter als 6 Monate)<\/li>\n<li>Einen amtlichen Lichtbildausweis: Das sind Reisepass, Personalausweis, E-Card etc.<\/li>\n<li>Foto von dir<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-41716\" src=\"https:\/\/iam-blog.gumlet.io\/blog\/wp-content\/uploads\/2024\/05\/Design-ohne-Titel-20-800x420.jpg\" alt=\"Klimaticket \u00d618\" width=\"800\" \/><\/p>\n<h3>Wird das gratis KlimaTicket \u00d618 sp\u00e4ter kostenpflichtig?<\/h3>\n<p>Die Infos auf der KlimaTicket-Homepage geben <strong>keinen Hinweis auf eine automatische Verl\u00e4ngerung<\/strong>. Das Gratisprogramm l\u00e4uft also nach 12 Monaten einfach aus, wenn du kein regelm\u00e4\u00dfiges SEPA-Lastschriftmandat angegeben hast.<\/p>\n<p>Das KlimaTicket ist aber nat\u00fcrlich immer eine praktische und umweltbewusste Entscheidung. F\u00fcr Personen bis einschlie\u00dflich 25 Jahre sind regul\u00e4r 821\u20ac im Jahr daf\u00fcr zu begleichen.<\/p>\n<p class=\"p1\"><span class=\"s1\"><div class=\"voucher-embed-iframe-wrapper\"><iframe title=\"Gutschein Frame\" data-src=\"https:\/\/www.schuelerrabatte.com\/at\/external\/widget\/newest?blog=1\" class=\"voucher-embed-iframe embed-blog lazy-load\" scrolling=\"no\" seamless=\"seamless\" frameBorder=\"0\" width=\"300\" height=\"160\" name=\"GutscheinFrame\"><\/iframe><\/div><\/span><\/p>\n<h3>Mit welchen \u00d6ffis kann ich mit dem KlimaTicket fahren?<\/h3>\n<p>Die besser Frage ist: Mit welchen nicht? Tourismusbahnen, Seilbahnen, Schibusse etc. sind oft ausgenommen. <a href=\"https:\/\/www.klimaticket.at\/gueltigkeitskarte\/\" target=\"_blank\" rel=\"noopener\">Hier findest du alle <strong>Ausnahmen<\/strong>.<\/a><\/p>\n<p>Generell kannst du aber<strong> so gut wie mit allen \u00d6ffis<\/strong> mit dem KlimaTicket fahren &#8211; <strong>ob regional oder \u00f6sterreichweit<\/strong>, ohne ein eigenes Ticket kaufen zu m\u00fcssen. Dazu geh\u00f6ren z. B. \u00d6BB, Westbahn, Wiener Linien, die IVB Betriebe, Grazer Linien, die O\u00d6VV, die Linz AG Linien, K\u00e4rntner Linien etc. Einfach einsteigen und los gehts!<\/p>\n<p><strong>Ab 3. Juni kannst du das kostenlose KlimaTicket \u00d618 beantragen!<\/strong><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfartige Neuigkeiten: Das gratis KlimaTicket \u00d618 kann dich ab 1. Juli \u00f6sterreichweit mit den \u00d6ffis kutschieren! Ob auch du Anspruch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[4],"tags":[8],"class_list":["post-109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisen","tag-oesterreich"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":5,"sum_votes":19},"media":"https:\/\/schuelerrabatte.gumlet.io\/blog\/wp-content\/uploads\/2024\/05\/Design-ohne-Titel-19-400x400.jpg","image":"https:\/\/schuelerrabatte.gumlet.io\/blog\/wp-content\/uploads\/2024\/05\/Design-ohne-Titel-19.jpg","title_plaintext":"Jetzt bekommst du das KlimaTicket 1 Jahr gratis!","text_plaintext":"Ab 1. Juli kannst du das KlimaTicket \u00d618 holen, mit dem du 1 Jahr gratis \u00d6ffis f\u00e4hrst! Welche Voraussetzungen daf\u00fcr gelten, kl\u00e4ren wir hier bei uns ab!","category":{"name":"Reisen","slug":"reisen"},"rating":{"best":0,"score":0,"avg":0,"votes":0},"publishpress_future_action":{"enabled":false,"date":"2025-06-19 11:55:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"tag_names":["\u00d6sterreich"],"tag_permalinks":["oesterreich"],"author_name":"Claudia","author_image":"https:\/\/secure.gravatar.com\/avatar\/666b128a642ebb02f1fe51370e522279?s=96&d=mm&r=g","_links":{"self":[{"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":5,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"predecessor-version":[{"id":115,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/posts\/109\/revisions\/115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/media\/111"}],"wp:attachment":[{"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schuelerrabatte.com\/blog\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}